{"id":2845,"count":1,"description":"","link":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/","name":"Brand D'YAVOL X","slug":"brand-dyavol-x","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brand D&#039;YAVOL X Archives - The Summer News Delhi | Latest Delhi News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brand D&#039;YAVOL X Archives - The Summer News Delhi | Latest Delhi News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/\" \/>\n<meta property=\"og:site_name\" content=\"The Summer News Delhi | Latest Delhi News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/index.php\\\/tag\\\/brand-dyavol-x\\\/\",\"url\":\"https:\\\/\\\/delhi.thesummernews.in\\\/index.php\\\/tag\\\/brand-dyavol-x\\\/\",\"name\":\"Brand D'YAVOL X Archives - The Summer News Delhi | Latest Delhi News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/index.php\\\/tag\\\/brand-dyavol-x\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/index.php\\\/tag\\\/brand-dyavol-x\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/delhi.thesummernews.in\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brand D'YAVOL X\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/#website\",\"url\":\"https:\\\/\\\/delhi.thesummernews.in\\\/\",\"name\":\"The Summer News Delhi | Latest Delhi News\",\"description\":\"The Summer News Delhi\",\"publisher\":{\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delhi.thesummernews.in\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/#organization\",\"name\":\"The Summer News\",\"url\":\"https:\\\/\\\/delhi.thesummernews.in\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/delhi.thesummernews.in\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGOSAMMAR.png\",\"contentUrl\":\"https:\\\/\\\/delhi.thesummernews.in\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGOSAMMAR.png\",\"width\":384,\"height\":159,\"caption\":\"The Summer News\"},\"image\":{\"@id\":\"https:\\\/\\\/delhi.thesummernews.in\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brand D'YAVOL X Archives - The Summer News Delhi | Latest Delhi News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/","og_locale":"en_US","og_type":"article","og_title":"Brand D'YAVOL X Archives - The Summer News Delhi | Latest Delhi News","og_url":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/","og_site_name":"The Summer News Delhi | Latest Delhi News","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/","url":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/","name":"Brand D'YAVOL X Archives - The Summer News Delhi | Latest Delhi News","isPartOf":{"@id":"https:\/\/delhi.thesummernews.in\/#website"},"breadcrumb":{"@id":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/delhi.thesummernews.in\/index.php\/tag\/brand-dyavol-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/delhi.thesummernews.in\/"},{"@type":"ListItem","position":2,"name":"Brand D'YAVOL X"}]},{"@type":"WebSite","@id":"https:\/\/delhi.thesummernews.in\/#website","url":"https:\/\/delhi.thesummernews.in\/","name":"The Summer News Delhi | Latest Delhi News","description":"The Summer News Delhi","publisher":{"@id":"https:\/\/delhi.thesummernews.in\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delhi.thesummernews.in\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/delhi.thesummernews.in\/#organization","name":"The Summer News","url":"https:\/\/delhi.thesummernews.in\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/delhi.thesummernews.in\/#\/schema\/logo\/image\/","url":"https:\/\/delhi.thesummernews.in\/wp-content\/uploads\/2023\/08\/LOGOSAMMAR.png","contentUrl":"https:\/\/delhi.thesummernews.in\/wp-content\/uploads\/2023\/08\/LOGOSAMMAR.png","width":384,"height":159,"caption":"The Summer News"},"image":{"@id":"https:\/\/delhi.thesummernews.in\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/delhi.thesummernews.in\/index.php\/wp-json\/wp\/v2\/tags\/2845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delhi.thesummernews.in\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/delhi.thesummernews.in\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/delhi.thesummernews.in\/index.php\/wp-json\/wp\/v2\/posts?tags=2845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}